{"id":260,"date":"2020-09-03T13:15:09","date_gmt":"2020-09-03T11:15:09","guid":{"rendered":"https:\/\/www.lenstore.it\/cura-degli-occhi\/?p=260"},"modified":"2023-05-25T13:20:05","modified_gmt":"2023-05-25T11:20:05","slug":"effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","status":"publish","type":"post","link":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","title":{"rendered":"Effetti dei dispositivi digitali sugli occhi: come proteggersi"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea-1024x684.jpg\" alt=\"gli effetti dei dispositivi digitali - luce blu - lenti a contatto \" class=\"wp-image-263\" srcset=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea-1024x684.jpg 1024w, https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea-300x200.jpg 300w, https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea-768x513.jpg 768w, https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg 1049w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Smartphone, tablet, e computer sono ormai diventati indispensabili nella vita di tutti i giorni per cercare ricette, fare shopping e guardare le serie preferite. Tuttavia, il tempo passato davanti ai loro schermi e l\u2019esposizione alla luce blu possono influenzare la nostra salute e quella dei nostro occhi.<\/p>\n\n\n\n<p>Come? Ecco di seguito una serie di sintomi da non sottovalutare ed alcuni consigli utili per proteggersi.<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong><em>Sindrome da visione al computer<\/em><\/strong><\/p>\n\n\n\n<p>Generalmente l\u2019esposizione prolungata allo schermo provoca fastidi quali secchezza e bruciore agli occhi,&nbsp;<a href=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/mal-di-testa-dietro-agli-occhi\/\">mal di testa<\/a> e dolori al collo dovuti alla posizione scorretta. <\/p>\n\n\n\n<p>Questo perch\u00e9 l\u2019abitudine di fissare un punto fisso per troppo tempo influenza il normale ammiccamento delle nostre palpebre, riducendone la lubrificazione. Se durante una conversazione sbattiamo le palpebre 22 volte al minuto o 10-15 volte mentre leggiamo, tutto si riduce a meno di 5 quando siamo al pc.<\/p>\n\n\n\n<p style=\"font-size:18px\"><em><strong>Luce blu<\/strong><\/em><\/p>\n\n\n\n<p>Come se non bastasse, tutti i dispositivi elettronici dotati di display si basano su una retroilluminazione di colore blu vicina all\u2019ultravioletto. Seppur permetta una visione chiara degli schermi, interferisce con la produzione di melatonina ed influenza il nostro ritmo biologico.<\/p>\n\n\n\n<p>Vi starete chiedendo a cosa serve la melatonina? E\u2019 un ormone responsabile dell\u2019equilibrio dormi-veglia e la sua interferenza pu\u00f2 provocare insonnia, ipersensibilit\u00e0, stress e poca concentrazione.&nbsp;&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong><em>Ma quali sono gli effetti sui nostri occhi?<\/em><\/strong><\/p>\n\n\n\n<p>Poich\u00e9 la nostra esposizione alla luce blu risale a 10-20 anni fa, i suoi effetti rimangono ancora poco conosciuti. Eppure, recenti studi sembrerebbero confermare un legame con la precoce degenerazione maculare della retina, oltre ad infiammazioni della cornea e patologie come la sindrome da occhio secco.<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong><em>Come proteggersi dai rischi nocivi del pc e dei  dispositivi elettronici?<\/em><\/strong><\/p>\n\n\n\n<p>Per proteggerci dai possibili danni dovuti al loro costante uso, nonch\u00e9 alla loro luce blu, ecco di seguito alcuni semplici rimedi:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Regola l&#8217;illuminazione dello schermo:<\/strong><br>Mentre la giornata lavorativa volge al termine e calcoli le ore trascorse a guardare uno schermo luminoso, potresti notare che i tuoi occhi si sentono sempre pi\u00f9 stanchi. Questo accade per un motivo molto semplice: se non c&#8217;\u00e8 abbastanza contrasto tra bianco e nero, i tuoi occhi faranno fatica a distinguere tra i diversi elementi sullo schermo, causando un affaticamento degli occhi. La soluzione \u00e8 molto semplice: abbassa la luminosit\u00e0 dello schermo e aumenta il contrasto. Ti sentirai immediatamente pi\u00f9 a tuo agio, poich\u00e9 l&#8217;illuminazione pi\u00f9 leggera ti aiuter\u00e0 a rilassare gli occhi.<\/li>\n\n\n\n<li><strong>Regola l&#8217;altezza del monitor:<\/strong><br>Gli occhi umani sono naturalmente posizionati per sostenere una specifica linea di sguardo. Se lo schermo del tuo computer non si trova nel tuo percorso &#8220;normale&#8221;, i tuoi occhi dovranno costantemente lavorare per guardare in una direzione innaturale. Gli esperti ottici suggeriscono di regolare l&#8217;altezza del monitor e posizionare lo schermo del computer non pi\u00f9 in alto rispetto all&#8217;altezza degli occhi; in particolare, tra 2 e 5 centimetri sotto il livello dei tuoi occhi quando sei seduto dritto. Ci\u00f2 contribuir\u00e0 a ridurre lo stress oculare.<\/li>\n\n\n\n<li><strong>Prenditi delle pause:<\/strong> <br>Se soffri di secchezza oculare e affaticamento degli occhi a causa del tuo uso continuo di dispositivi digitali, prova ad adottare la regola 20-20. Ogni 20 minuti trascorri 20 secondi guardando qualcos\u2019altro a qualche metro di distanza. Le pause brevi frequenti sono migliori di quelle lunghe; se non hai voglia di fare una pausa caff\u00e8 ogni ora, puoi eseguire un esercizio oculare molto semplice mentre sei seduto alla tua scrivania. Basta distogliere lo sguardo e concentrarsi su un oggetto distante, per rilassare i muscoli focalizzati nei tuoi occhi.<\/li>\n\n\n\n<li><strong>Mantieni gli occhi idratati:<\/strong> Lubrificare gli occhi con dei colliri pu\u00f2 aiutare a prevenire le sensazioni di disagio associate agli occhi secchi. Uno dei motivi per cui potresti soffrire di secchezza oculare a casa davanti al pc \u00e8 la riduzione del battito delle palpebre. Mentre la persona media lo fa circa 20 volte al minuto, prova a batterte le palpebre solo 7 volte al minuto quando trascorri lunghi periodi di tempo davanti a uno schermo. Il battito delle&nbsp;palpebre aiuta l&#8217;occhio a eliminare le particelle di polvere e diffonde oli e fluidi lubrificanti sulla superficie dell&#8217;occhio per mantenere gli occhi idratati e sani. I colliri hanno lo stesso scopo, mantenendo gli occhi umidi quando il battito delle palpebre \u00e8 al minimo.<\/li>\n<\/ul>\n\n\n\n<p>Il <a href=\"https:\/\/www.lenstore.it\/gocce-per-occhi\/p120\/blink-intensive-tears-collirio\" target=\"_blank\" rel=\"noreferrer noopener\">collirio Blink Intensive Tear<\/a><a href=\"http:\/\/index.php?_a=viewProd&amp;productId=120\" target=\"_blank\" rel=\"noreferrer noopener\">s<\/a> \u00e8 specificamente formulato per lenire e proteggere gli occhi secchi o irritati. Con la sua formula viscoelastica, replica le lacrime umane per ripristinare il film lacrimale e offre&nbsp;un comfort eccezionale, sicuro e delicato per gli occhi. Disponibili anche in flaconcini monouso, queste gocce idratanti sono ideali e convenienti per l&#8217;uso quotidiano durante il giorno, e si pu\u00f2 usare anche indossando le <a href=\"https:\/\/www.lenstore.it\/b317\/lenti-a-contatto\" target=\"_blank\" rel=\"noreferrer noopener\">lenti a contatto<\/a>.<\/p>\n\n\n\n<p>Infine, potrebbe essere utile l\u2019uso di occhiali da vista con filtro luce blu quando siamo al lavoro, <a href=\"https:\/\/www.lenstore.it\/c107\/spray-per-occhi-e-accessori\" target=\"_blank\" rel=\"noreferrer noopener\">spray<\/a> o <a href=\"https:\/\/www.lenstore.it\/c104\/colliri\" target=\"_blank\" rel=\"noreferrer noopener\">colliri<\/a> per occhi secchi e irritati. E perch\u00e9 no, una delle tante app che permettono di impostare diverse modalit\u00e0 notte, riducendo la potenza del led e salvaguardare la nostra vista.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Smartphone, tablet, e computer sono ormai diventati indispensabili nella vita di tutti i giorni per cercare ricette, [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salute-degli-occhi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore<\/title>\n<meta name=\"description\" content=\"L&#039; esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore\" \/>\n<meta property=\"og:description\" content=\"L&#039; esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\" \/>\n<meta property=\"og:site_name\" content=\"Lenstore\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-03T11:15:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-25T11:20:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1049\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rosariacusatis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"rosariacusatis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\"},\"author\":{\"name\":\"rosariacusatis\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#\/schema\/person\/cde11187ea0c9322d8dd850a012a29f3\"},\"headline\":\"Effetti dei dispositivi digitali sugli occhi: come proteggersi\",\"datePublished\":\"2020-09-03T11:15:09+00:00\",\"dateModified\":\"2023-05-25T11:20:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\"},\"wordCount\":830,\"publisher\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg\",\"articleSection\":[\"Salute degli occhi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\",\"url\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\",\"name\":\"Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore\",\"isPartOf\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg\",\"datePublished\":\"2020-09-03T11:15:09+00:00\",\"dateModified\":\"2023-05-25T11:20:05+00:00\",\"description\":\"L' esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage\",\"url\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg\",\"contentUrl\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg\",\"width\":1049,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Effetti dei dispositivi digitali sugli occhi: come proteggersi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#website\",\"url\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/\",\"name\":\"Lenstore\",\"description\":\"Guida alle lenti | Salute | Stile di vita\",\"publisher\":{\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lenstore.it\/#organization\",\"name\":\"Lenstore\",\"url\":\"https:\/\/www.lenstore.it\",\"logo\":\"https:\/\/www.lenstore.it\/png\/lenstore-logo.png\",\"image\":\"https:\/\/www.lenstore.it\/png\/lenstore-logo.png\",\"companyRegistration\":\"51990\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"customer service\",\"telephone\":\"051 0920502\",\"email\":\"assistenza@lenstore.it\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/#\/schema\/person\/cde11187ea0c9322d8dd850a012a29f3\",\"name\":\"rosariacusatis\",\"url\":\"https:\/\/www.lenstore.it\/cura-degli-occhi\/author\/rosariacusatis\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore","description":"L' esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","og_locale":"it_IT","og_type":"article","og_title":"Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore","og_description":"L' esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.","og_url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","og_site_name":"Lenstore","article_published_time":"2020-09-03T11:15:09+00:00","article_modified_time":"2023-05-25T11:20:05+00:00","og_image":[{"width":1049,"height":701,"url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","type":"image\/jpeg"}],"author":"rosariacusatis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"rosariacusatis","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#article","isPartOf":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi"},"author":{"name":"rosariacusatis","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#\/schema\/person\/cde11187ea0c9322d8dd850a012a29f3"},"headline":"Effetti dei dispositivi digitali sugli occhi: come proteggersi","datePublished":"2020-09-03T11:15:09+00:00","dateModified":"2023-05-25T11:20:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi"},"wordCount":830,"publisher":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#organization"},"image":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage"},"thumbnailUrl":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","articleSection":["Salute degli occhi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi","name":"Effetti dei dispositivi digitali sugli occhi: come proteggersi - Lenstore","isPartOf":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage"},"image":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage"},"thumbnailUrl":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","datePublished":"2020-09-03T11:15:09+00:00","dateModified":"2023-05-25T11:20:05+00:00","description":"L' esposizione alla luce dei dispositivi digitali pu\u00f3 influenzare la nostra salute e quella dei nostro occhi. Consulta alcuni consigli utili per proteggersi.","breadcrumb":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#primaryimage","url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","contentUrl":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","width":1049,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/effetti-dei-dispositivi-digitali-sugli-occhi-come-proteggersi#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lenstore.it\/cura-degli-occhi"},{"@type":"ListItem","position":2,"name":"Effetti dei dispositivi digitali sugli occhi: come proteggersi"}]},{"@type":"WebSite","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#website","url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/","name":"Lenstore","description":"Guida alle lenti | Salute | Stile di vita","publisher":{"@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lenstore.it\/cura-degli-occhi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.lenstore.it\/#organization","name":"Lenstore","url":"https:\/\/www.lenstore.it","logo":"https:\/\/www.lenstore.it\/png\/lenstore-logo.png","image":"https:\/\/www.lenstore.it\/png\/lenstore-logo.png","companyRegistration":"51990","contactPoint":{"@type":"ContactPoint","contactType":"customer service","telephone":"051 0920502","email":"assistenza@lenstore.it"}},{"@type":"Person","@id":"https:\/\/www.lenstore.it\/cura-degli-occhi\/#\/schema\/person\/cde11187ea0c9322d8dd850a012a29f3","name":"rosariacusatis","url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/author\/rosariacusatis"}]}},"jetpack_featured_media_url":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-content\/uploads\/sites\/2\/2020\/09\/photo-1448932223592-d1fc686e76ea.jpg","order_on_store":null,"_links":{"self":[{"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/posts\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":45,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/posts\/260\/revisions"}],"predecessor-version":[{"id":2644,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/posts\/260\/revisions\/2644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/media\/263"}],"wp:attachment":[{"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/media?parent=260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/categories?post=260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lenstore.it\/cura-degli-occhi\/wp-json\/wp\/v2\/tags?post=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}